{"id":524,"date":"2024-07-11T12:25:36","date_gmt":"2024-07-11T12:25:36","guid":{"rendered":"https:\/\/demo.wprise.co\/HandyFix\/?page_id=524"},"modified":"2024-07-12T07:15:02","modified_gmt":"2024-07-12T07:15:02","slug":"contact","status":"publish","type":"page","link":"https:\/\/demo.wprise.co\/HandyFix\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"524\" class=\"elementor elementor-524\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da4c0ac e-flex e-con-boxed e-con e-parent\" data-id=\"da4c0ac\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf7f035 e-con-full e-flex e-con e-child\" data-id=\"cf7f035\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8c77ab3 e-con-full e-flex e-con e-child\" data-id=\"8c77ab3\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-08428bb e-con-full e-flex e-con e-child\" data-id=\"08428bb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c3b8c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a6c3b8c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/wprise.co\/\" target=\"_blank\">Contact Us\n<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee29ac8 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ee29ac8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\tAny questions? We would happy to help you!\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e9505a e-con-full e-flex e-con e-child\" data-id=\"9e9505a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0c1e5ac e-con-full e-flex e-con e-child\" data-id=\"0c1e5ac\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-473babb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"473babb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/demo.wprise.co\/HandyFix\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(877)-555-6666<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c1579a e-con-full e-flex e-con e-child\" data-id=\"6c1579a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8b337 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"ee8b337\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ti ti-email\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@domain.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9f1835 e-con-full e-flex e-con e-child\" data-id=\"a9f1835\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14f9ec6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"14f9ec6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"ti ti-location-pin\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">123 Main Street, Suite 101, Cityville<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9747ffb e-con-full e-flex e-con e-child\" data-id=\"9747ffb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-369dab0 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"369dab0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-ti-facebook elementor-repeater-item-2721f46\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Ti-facebook<\/span>\n\t\t\t\t\t\t<i class=\"ti ti-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-x-twitter elementor-repeater-item-8e67113\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">X-twitter<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-3298693\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b95b708 e-con-full e-flex e-con e-child\" data-id=\"b95b708\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-961d2ce elementor-widget__width-inherit elementor-widget elementor-widget-bdt-wp-forms\" data-id=\"961d2ce\" data-element_type=\"widget\" data-widget_type=\"bdt-wp-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-538\"><form id=\"wpforms-form-538\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"538\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/HandyFix\/wp-json\/wp\/v2\/pages\/524\" data-token=\"bb9581f34ec53a8e94783187cb406711\" data-token-time=\"1788372390\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-538-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-538-field_3\">Full Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-538-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Jhon Doe\" aria-errormessage=\"wpforms-538-field_3-error\" required><\/div><div id=\"wpforms-538-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-538-field_1\">Email Address <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-538-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"info@domain.com\" spellcheck=\"false\" aria-errormessage=\"wpforms-538-field_1-error\" required><\/div><div id=\"wpforms-538-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-538-field_4\">Phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-538-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"xxx-xxx-xxx\" aria-errormessage=\"wpforms-538-field_4-error\" required><\/div><div id=\"wpforms-538-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-538-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-538-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Write Your Message\" aria-errormessage=\"wpforms-538-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"538\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/pages\/524\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-538\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send Message\" aria-live=\"assertive\" value=\"wpforms-submit\">Send Message<\/button><img decoding=\"async\" src=\"https:\/\/demo.wprise.co\/HandyFix\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eef7b2a e-flex e-con-boxed e-con e-parent\" data-id=\"eef7b2a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-682e83d e-con-full e-flex e-con e-child\" data-id=\"682e83d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-52d2fba e-con-full e-flex e-con e-child\" data-id=\"52d2fba\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7dc17f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c7dc17f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently asked questions\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a52ee66 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a52ee66\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEach member of our team brings a unique set of skills.\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11dcdce e-con-full e-flex e-con e-child\" data-id=\"11dcdce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3826591 elementor-invisible elementor-widget elementor-widget-bdt-accordion\" data-id=\"3826591\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;100&quot;}\" data-widget_type=\"bdt-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-accordion-container\">\n\t\t\t<div id=\"bdt-ep-accordion-3826591\" class=\"bdt-ep-accordion bdt-accordion\" data-bdt-accordion=\"{&quot;collapsible&quot;:true,&quot;multiple&quot;:false,&quot;transition&quot;:&quot;ease-in-out&quot;}\" \t\tdata-settings=\"{&quot;id&quot;:&quot;bdt-ep-accordion-3826591&quot;,&quot;activeHash&quot;:&quot;no&quot;,&quot;activeScrollspy&quot;:null,&quot;hashTopOffset&quot;:false,&quot;hashScrollspyTime&quot;:false}\">\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-accordion-item\">\n\t\t\t\t\t\t<h3\t\t\t\t\t\t\tclass=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"\n\t\t\t\t\t\t\tbdt-ep-accordion-what-services-does-activa-digital-agency-provide\"\n\t\t\t\t\t\t\tdata-accordion-index=\"0\" data-title=\"what-services-does-activa-digital-agency-provide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon bdt-flex-align-right\"\n\t\t\t\t\t\t\t\t\taria-hidden=\"true\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-closed\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-plus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-opened\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-minus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span role=\"heading\" class=\"bdt-ep-title-text bdt-display-inline-block\" >\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t What services does Activa Digital Agency provide?\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n\t\t\t\t\t\t\tActiva Digital Agency offers a wide range of digital services, including website design and development, digital marketing strategies, search engine optimization.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-accordion-item\">\n\t\t\t\t\t\t<h3\t\t\t\t\t\t\tclass=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"\n\t\t\t\t\t\t\tbdt-ep-accordion-how-does-activa-digital-agency-ensure-the-success-of-its-clients-projects\"\n\t\t\t\t\t\t\tdata-accordion-index=\"1\" data-title=\"how-does-activa-digital-agency-ensure-the-success-of-its-clients-039-projects\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon bdt-flex-align-right\"\n\t\t\t\t\t\t\t\t\taria-hidden=\"true\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-closed\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-plus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-opened\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-minus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span role=\"heading\" class=\"bdt-ep-title-text bdt-display-inline-block\" >\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tHow does Activa Digital Agency ensure the success of its clients&#039; projects?\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n\t\t\t\t\t\t\tActiva Digital Agency offers a wide range of digital services, including website design and development, digital marketing strategies, search engine optimization.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-accordion-item\">\n\t\t\t\t\t\t<h3\t\t\t\t\t\t\tclass=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"\n\t\t\t\t\t\t\tbdt-ep-accordion-is-activa-digital-agency-experienced-in-working-with-businesses-of-all-sizes\"\n\t\t\t\t\t\t\tdata-accordion-index=\"2\" data-title=\"is-activa-digital-agency-experienced-in-working-with-businesses-of-all-sizes\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon bdt-flex-align-right\"\n\t\t\t\t\t\t\t\t\taria-hidden=\"true\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-closed\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-plus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-opened\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-minus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span role=\"heading\" class=\"bdt-ep-title-text bdt-display-inline-block\" >\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tIs Activa Digital Agency experienced in working with businesses of all sizes?\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n\t\t\t\t\t\t\tActiva Digital Agency offers a wide range of digital services, including website design and development, digital marketing strategies, search engine optimization.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-accordion-item\">\n\t\t\t\t\t\t<h3\t\t\t\t\t\t\tclass=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"\n\t\t\t\t\t\t\tbdt-ep-accordion-how-can-i-request-a-quote-or-discuss-a-potential-project-with-activa-digital-agency\"\n\t\t\t\t\t\t\tdata-accordion-index=\"3\" data-title=\"how-can-i-request-a-quote-or-discuss-a-potential-project-with-activa-digital-agency\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon bdt-flex-align-right\"\n\t\t\t\t\t\t\t\t\taria-hidden=\"true\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-closed\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-plus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-opened\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-minus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span role=\"heading\" class=\"bdt-ep-title-text bdt-display-inline-block\" >\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tHow can I request a quote or discuss a potential project with Activa Digital Agency?\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n\t\t\t\t\t\t\tActiva Digital Agency offers a wide range of digital services, including website design and development, digital marketing strategies, search engine optimization.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-accordion-item\">\n\t\t\t\t\t\t<h3\t\t\t\t\t\t\tclass=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"\n\t\t\t\t\t\t\tbdt-ep-accordion-does-activa-digital-agency-provide-ongoing-support-and-maintenance-after-project-completion\"\n\t\t\t\t\t\t\tdata-accordion-index=\"4\" data-title=\"does-activa-digital-agency-provide-ongoing-support-and-maintenance-after-project-completion\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon bdt-flex-align-right\"\n\t\t\t\t\t\t\t\t\taria-hidden=\"true\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-closed\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-plus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ep-accordion-icon-opened\">\n\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw ti ti-minus\"><\/i>\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span role=\"heading\" class=\"bdt-ep-title-text bdt-display-inline-block\" >\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDoes Activa Digital Agency provide ongoing support and maintenance after project completion?\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n\t\t\t\t\t\t\tActiva Digital Agency offers a wide range of digital services, including website design and development, digital marketing strategies, search engine optimization.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact Us Any questions? We would happy to help you! (877)-555-6666 info@domain.com 123 Main Street, Suite 101, Cityville Ti-facebook X-twitter Instagram Frequently [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-524","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/pages\/524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":49,"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/pages\/524\/revisions"}],"predecessor-version":[{"id":699,"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/pages\/524\/revisions\/699"}],"wp:attachment":[{"href":"https:\/\/demo.wprise.co\/HandyFix\/wp-json\/wp\/v2\/media?parent=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}